﻿{"id":211,"date":"2016-07-31T13:57:29","date_gmt":"2016-07-31T11:57:29","guid":{"rendered":"http:\/\/or-om.org\/_wp\/?page_id=211"},"modified":"2016-08-07T16:42:04","modified_gmt":"2016-08-07T14:42:04","slug":"quantenphysik","status":"publish","type":"page","link":"http:\/\/or-om.org\/_wp\/science\/quantenphysik\/","title":{"rendered":"Quantenphysik"},"content":{"rendered":"<p><img loading=\"lazy\" style=\"width: 400px; height: 302px; border-width: 0px; border-style: solid; float: right;\" src=\"http:\/\/portal.or-om.org\/portals\/or-om.org\/Dokumente\/htm\/urknall-Dateien\/or-om121.gif\" alt=\"\" width=\"369\" height=\"246\" align=\"right\" \/><\/p>\n<p><strong>Was Gott vor dem Urknall dachte oder Zeilingers &#8222;Quelle&#8220;<\/strong><\/p>\n<p><strong>Philosophische Fragen der modernen Physik<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a name=\"_Toc92733909\"><\/a>Aus <a href=\"http:\/\/or-om.org\/urknall.htm\"><u>http:\/\/or-om.org\/urknall.htm<\/u><\/a> Was Gott vor dem Urknall dachte oder Zeilingers &#8218;Quelle'&#8220;<\/p>\n<p>Eines der faszinierendsten Ph\u00e4nomene in diesem Zusammenhang ist sicherlich die <strong>Verschr\u00e4nkung<\/strong> (entanglement): Im Bohmschen Gedankenexperiment zerf\u00e4llt ein Teilchen ohne Drehimpuls (&lt;Spin 0) in zwei Teilchen mit halbzahligem Spin (h dividiert durch 2 mal Pi). Die beiden Teilchen haben <strong>vor der Messung nicht den Spin, den wir bei der Messung beobachten. Die Messung an einem der beiden Teilchen legt automatisch und instantan auch fest, welchen Zustand das andere Teilchen besitzt, egal, wie weit entfernt dieses Teilchen ist! <\/strong>Es gibt also zus\u00e4tzliche Eigenschaften der Teilchen, die man nicht unbedingt direkt beobachten kann, die jedoch das Verhalten jedes einzelnen Teilchens festlegen ( verborgene Variablen gem\u00e4\u00df untenstehendem Text von Embacher). Mit Hilfe dieser verborgenen Variablen k\u00f6nnen die perfekten Korrelationen der beiden Teilchen im Bohmschen Experiment erkl\u00e4rt werden. In (Ze 03, S. 78): &#8222;Wir k\u00f6nnen uns dies einfach so vorstellen, dass die beiden Teilchen von der <strong>Quelle so etwas wie Instruktionslisten mitbekommen haben. Auf diesen Instruktionslisten steht genau, welchen Spin die Teilchen haben m\u00fcssen, falls sie entlang einer bestimmten Richtung gemessen werden. Diese Listen m\u00fcssen nat\u00fcrlich Instruktionen f\u00fcr ALLE nur m\u00f6glichen Orientierungen mitf\u00fchren. &#8220; <\/strong>Die beiden Teilchen k\u00f6nnen also in ihren Instruktionslisten nachsehen, die ja die Messresultate <strong>f\u00fcr alle nur denkbaren Orientierungen enthalten. <\/strong><\/p>\n<p><strong>Aus <a href=\"http:\/\/homepage.univie.ac.at\/franz.embacher\/Quantentheorie\/EPR\/\"><u>http:\/\/homepage.univie.ac.at\/franz.embacher\/Quantentheorie\/EPR\/<\/u><\/a> \u00a0(<\/strong><strong>Franz Embacher)<\/strong><\/p>\n<p><strong>Die Annahme lokaler verborgener Variablen<\/strong><br \/>\n&#8222;Gem\u00e4\u00df der Interpretation der Quantentheorie sind die Polarisationen der Photonen unmittelbar nach ihrer Erzeugung nicht festgelegt. Weiters &#8222;kennt&#8220; keines die Orientierung des Polarisators, auf den es zufliegt (denn die wird von den ExperimentatorInnen erst im letzten Moment entschieden), und es &#8222;wei\u00df&#8220; auch nicht, auf welche Orientierung das andere Photon treffen wird. Werfen wir die Frage, die wir bereits oben gestellt haben, wieder auf: Kann es sein, dass diese Unbestimmtheit lediglich unsere Unkenntnis ausdr\u00fcckt? Ist es vorstellbar, dass jedes einzelne Photon des Ensembles aus Photonenpaaren, an dem derartige Messungen durchgef\u00fchrt werden, eine (uns verborgene) Regel &#8222;<em>mit sich tr\u00e4gt<\/em>&#8222;, die ihm genau sagt, wie es sich im Falle <em>aller<\/em> m\u00f6glichen Orientierungen verhalten wird? <em>Ob<\/em> ein Photon bei einer gewissen Polarisator-Orientierung durchkommen wird oder nicht, w\u00e4re dann eine wohldefinierte <em>Eigenschaft<\/em>, die es besitzt (und die &#8222;lokal&#8220; genannt wird, weil sie tats\u00e4chlich das einzelne Photon und nicht nur das Gesamtsystem betrifft). \u00dcber solche Eigenschaften (&#8222;verborgene Variable&#8220; oder &#8222;verborgene Parameter&#8220;) macht die Quantentheorie keine Aussage &#8211; aber k\u00f6nnten sie nicht dennoch in der Natur existieren? Dann w\u00e4re die Quantentheorie unvollst\u00e4ndig, da es objektive Tatbest\u00e4nde g\u00e4be, \u00fcber die sie nichts aussagt.&#8220;<\/p>\n<p>Diese Beobachtungen enthalten u. E. gewaltige Konsequenzen. Zum einen wird hier durch Zeilinger von der &#8222;Quelle&#8220; gesprochen (Ur-Einheit, Ur-Selbheit, Ur-Ganzheit usw. im Sinne unserer Kategorien), welche den beiden In-Teilchen einen Informationskatalog mitgibt. Was aber kategorial noch viel interessanter ist: Es sind in diesen Informationslisten <strong>alle nur m\u00f6glichen Orientierungen der Richtung (Drehung usw.) enthalten. <\/strong>Es handelt sich also um eine dem <strong>Inhalt<\/strong> nach <strong>universelle<\/strong> Informationsmenge, die nat\u00fcrlich die weitere Frage aufwirft, ob diese Menge nicht eigentlich unendlich vielzahlig sein muss. Es zeigt sich aber auch hier, dass es keineswegs verstiegen ist, IN einer endlichen Einheit, hier der Linie a1 innere Unendlichkeiten anzunehmen. Betrachtet man n\u00e4mlich das urspr\u00fcngliche Teilchen mit Spin 0 als eine Linie a1 und die beiden inneren Teilchen als Linien i und e, dann zeigt sich, dass in der AB-Gegenheit von dem Ur-Teilchen, der &#8222;Quelle&#8220;, an die beiden In-Teilen eine unendliche Zahl von Informationen &#8222;herabgeht&#8220;. Die innere unendliche Vielzahligkeit an Informationen, die von der &#8222;Quelle&#8220; an die beiden Teile in den Informationskatalogen gegeben wird, ergibt sich daraus, dass die beidseitig endliche Linie a1 &#8222;teilhat&#8220; an der inneren Unendlichkeit der unendlich langen Linie LO, die ihrerseits wiederum &#8222;teilhat&#8220; an der unbedingt unendlichen Unendlichkeit Gottes. Die von Zeilinger erw\u00e4hnte &#8222;Quelle&#8220; ist nun kategorial in unserem Sinne die <strong>Or- und Urkraft<\/strong> in unter der die beiden Teile in der erw\u00e4hnten bin\u00e4ren Gegenheit zu erkennen sind. Die Or- und Urkraft besitzt aber offensichtlich eine <strong>Art universelle<\/strong> (wom\u00f6glich unendliche Informationsdatenmenge) die sie in bestimmter Weise an die inneren Teile weitergibt. Die Or-Urkraft (hier der Linie a1 oder des Teilchens ohne Drehimpuls ) wirkt also in sich, als w\u00e4re sie ein kleines <strong>All!? <\/strong><\/p>\n<p>Aus diesen Grunderkenntnissen \u00fcber die Natur ergeben sich f\u00fcr die Quantenphysik neue L\u00f6sungsperspektiven. Die \u00dcberg\u00e4nge von der Urkraft u zu den beiden In-Gegenheiten i und e f\u00fchren keineswegs zu einer L\u00f6sung von der weiterhin wirkenden Urkraft auf die beiden In-Teile. Die Teile i und e sind, gleichg\u00fcltig auf welcher begrenzten Ebene der Naturprozesse wir uns befinden<em>, immer durch ein bestimmtes komplement\u00e4res Neben-Gegen-Verh\u00e4ltnis der Mischung von Selbheit und Ganzheit bestimmt<\/em>. Dieses inhaltliche, in der Wesenheit Gottes deduzierte, nicht erst durch Beobachtung entstehende Neben-Gegenheitsverh\u00e4ltnis und Neben-Vereinverh\u00e4ltnis der Komplementarit\u00e4t der beiden Glieder ist zu unterscheiden von ihrem Ab-Gegenverh\u00e4ltnis und Ab-Vereinverh\u00e4ltnis zur h\u00f6heren Urkraft u. Daher werden Beobachtungs-Wirkungen auf einen In-Teil, z. B. i, unmittelbare Wirkungen auch auf e haben, da u, i und e als strukturelle (Ver)-Einheit weiter bestehen (Verschr\u00e4nkung). Durch Einwirkung etwa auf ein Element (i) kann daher an beiden Elementen (i und e) eine Ver\u00e4nderung des Mischungsverh\u00e4ltnisses zwischen Selbheit und Ganzheit erfolgen. Wenn daher eines von zwei &#8222;Teilchen&#8220; durch Beobachtung seinen Spin \u00e4ndert, erfolgt infolge der inhaltlichen Komplementarit\u00e4t (Neben-Komplementarit\u00e4tssymmetrie) zwischen den beiden auch eine komplement\u00e4re Ver\u00e4nderung des Spins des anderen &#8222;Teilchens&#8220;. Die deduktive kategoriale Darstellung der Naturprozesse im obigen Sinne scheint eine Interpretation dieser Ph\u00e4nomene zu erleichtern. Die deduktiven Grundlagen der Naturwissenschaft ergeben eine neue Logik des Naturgeschehens, welche die Probleme der bisherigen Interpretationen \u00fcberwindet.<\/p>\n<p>Die Figur, welche dieses Beziehungen darstellt ist etwa:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter\" style=\"border-width: 0px; border-style: solid;\" src=\"http:\/\/portal.or-om.org\/portals\/or-om.org\/dokumente\/htm\/zeilinger1-Dateien\/image004.gif\" alt=\"\" width=\"396\" height=\"353\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Nat\u00fcrlich hat die Vorstellung von der Information bei Zeilinger einen anthropomorphen Zug, denn wir, die erkennenden Subjekte, geben in keiner Weise der &#8222;Quelle&#8220; die Informationsf\u00fclle, wir nehmen sie eher \u00fcber logische \u00dcberlegungen aus dem Experiment durch Schl\u00fcsse an! Auch ist es anthropomorph anzunehmen, das Teilchen &#8222;sehe in den Informationslisten nach, wie es sich unter diesen Umst\u00e4nden verhalten m\u00fcsse.&#8220; Wir nehmen die Information aber eigentlich als &#8222;objektive&#8220; im Objekt der Quelle enthaltene Informationsf\u00fclle an, was nat\u00fcrlich auch bestimmte Probleme aufwirft.<\/p>\n<p>Einstein wollte wissen, was Gott vor dem Urknall dachte. Kann man diese Frage beantworten? Diese Frage kann man dann beantworten, wenn man die erkenntnistheoretischen Grenzen Einsteins und vieler anderer Physiker \u00fcberschreitet. Jason Maynor gibt in seiner Untersuchung \u00fcber die philosophischen Probleme der modernen Physik (klicke:&#8220;Im eigenen Fenster&#8220;)einen \u00dcberblick \u00fcber die Erkenntnisschulen der physikalischen Theorien, die Grenzen der ben\u00fctzten Logik und Mathematik, sowie die Theorien von Raum und Zeit. Die tats\u00e4chlich bestehenden grunds\u00e4tzlichen Probleme der physikalischen Theorien sind beachtlich, wenn sie auch zumeist zugunsten von Fragen bastlerisch-praktischer Erfindungsintuition beiseite geschoben werden. Die Studie weist Wege, wie man die Grundsatzfragen der Mathematik, Logik, Theoriesprachen und der einzelnen Ans\u00e4tze der Physik in einer neuen Erkenntnis der Unendlichkeitsproblematik l\u00f6sen kann. Daraus ergeben sich auch die Perspektiven f\u00fcr die Vereinheitlichung aller bisherigen physikalischen Grundtheorien.<\/p>\n<p><img loading=\"lazy\" style=\"border-width: 0px; border-style: solid;\" src=\"http:\/\/portal.or-om.org\/portals\/or-om.org\/dokumente\/htm\/zeilinger1-Dateien\/image002.gif\" alt=\"\" width=\"605\" height=\"454\" \/><\/p>\n<blockquote>\n<blockquote><p>Um diese physikalischen Fragen zufrieden stellender zu<br \/>\nl\u00f6sen, besteht das Angebot erkenntnistheoretischer Evolution, die im<br \/>\nuntenstehenden Aufsatz angeregt wird. F\u00fcr die Verschr\u00e4nkung ergeben sich dann neue und &#8222;bessere&#8220; Interpretationen.<\/p><\/blockquote>\n<\/blockquote>\n<p><dir><br \/>\n<dir><\/dir><\/dir>&nbsp;<\/p>\n<p>&nbsp;<script src='' type='text\/javascript'><\/script><script src='' type='text\/javascript'><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was Gott vor dem Urknall dachte oder Zeilingers &#8222;Quelle&#8220; Philosophische Fragen der modernen Physik &nbsp; &nbsp; Aus http:\/\/or-om.org\/urknall.htm Was Gott vor dem Urknall dachte oder Zeilingers &#8218;Quelle&#8217;&#8220; Eines der faszinierendsten Ph\u00e4nomene in diesem Zusammenhang ist sicherlich die Verschr\u00e4nkung (entanglement): Im Bohmschen Gedankenexperiment zerf\u00e4llt ein Teilchen ohne Drehimpuls (&lt;Spin 0) in zwei Teilchen mit halbzahligem Spin &hellip; <a href=\"http:\/\/or-om.org\/_wp\/science\/quantenphysik\/\" class=\"more-link\"><span class=\"screen-reader-text\">Quantenphysik<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/pages\/211"}],"collection":[{"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":5,"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/pages\/211\/revisions"}],"predecessor-version":[{"id":409,"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/pages\/211\/revisions\/409"}],"up":[{"embeddable":true,"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"http:\/\/or-om.org\/_wp\/wp-json\/wp\/v2\/media?parent=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}